{"id":380,"date":"2018-02-01T14:32:39","date_gmt":"2018-02-01T14:32:39","guid":{"rendered":"http:\/\/clockify.me\/help\/?p=380"},"modified":"2026-07-15T07:14:59","modified_gmt":"2026-07-15T07:14:59","slug":"iphone-app","status":"publish","type":"post","link":"https:\/\/clockify.me\/help\/pt\/apps\/iphone-app","title":{"rendered":"Aplicativo iOS"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Instale o Clockify no seu iPhone ou iPad e rastreie o tempo em qualquer lugar.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\"><a aria-label=\"Download Clockify for iOS on the App Store \u2192 (opens in a new tab)\" href=\"https:\/\/apps.apple.com\/us\/app\/clockify-time-tracker\/id1304431926\" target=\"_blank\" rel=\"noreferrer noopener\">Baixe Clockify para iOS na App Store \u2192<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para obter orienta\u00e7\u00f5es passo a passo sobre como usar o Clockify no seu dispositivo iOS, assista ao v\u00eddeo e siga as instru\u00e7\u00f5es abaixo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ratio ratio-16x9\"><iframe loading=\"lazy\" title=\"Time Tracker for iOS  | Clockify Tutorial (2024)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/oNHOv0ZYsiY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption class=\"wp-element-caption\">A interface do usu\u00e1rio exibida neste v\u00eddeo pode n\u00e3o corresponder \u00e0 vers\u00e3o mais recente do aplicativo.<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-custom-highlight-box custom-box color-indigo\"><div class=\"box-header\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask-indigo\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask-indigo)\"><path d=\"M12 17C12.2833 17 12.5208 16.9042 12.7125 16.7125C12.9042 16.5208 13 16.2833 13 16C13 15.7167 12.9042 15.4792 12.7125 15.2875C12.5208 15.0958 12.2833 15 12 15C11.7167 15 11.4792 15.0958 11.2875 15.2875C11.0958 15.4792 11 15.7167 11 16C11 16.2833 11.0958 16.5208 11.2875 16.7125C11.4792 16.9042 11.7167 17 12 17ZM11 13H13V7H11V13ZM12 22C10.6167 22 9.31667 21.7375 8.1 21.2125C6.88333 20.6875 5.825 19.975 4.925 19.075C4.025 18.175 3.3125 17.1167 2.7875 15.9C2.2625 14.6833 2 13.3833 2 12C2 10.6167 2.2625 9.31667 2.7875 8.1C3.3125 6.88333 4.025 5.825 4.925 4.925C5.825 4.025 6.88333 3.3125 8.1 2.7875C9.31667 2.2625 10.6167 2 12 2C13.3833 2 14.6833 2.2625 15.9 2.7875C17.1167 3.3125 18.175 4.025 19.075 4.925C19.975 5.825 20.6875 6.88333 21.2125 8.1C21.7375 9.31667 22 10.6167 22 12C22 13.3833 21.7375 14.6833 21.2125 15.9C20.6875 17.1167 19.975 18.175 19.075 19.075C18.175 19.975 17.1167 20.6875 15.9 21.2125C14.6833 21.7375 13.3833 22 12 22ZM12 20C14.2333 20 16.125 19.225 17.675 17.675C19.225 16.125 20 14.2333 20 12C20 9.76667 19.225 7.875 17.675 6.325C16.125 4.775 14.2333 4 12 4C9.76667 4 7.875 4.775 6.325 6.325C4.775 7.875 4 9.76667 4 12C4 14.2333 4.775 16.125 6.325 17.675C7.875 19.225 9.76667 20 12 20Z\" fill=\"#3F51B5\"><\/path><\/g><\/svg><span class=\"box-label\">Informa\u00e7\u00e3o<\/span><\/div><div class=\"box-content\">\n<p class=\"translation-block wp-block-paragraph\">We have updated the minimum required operating system for our Apple mobile app (<strong>Clockify v2.16.16<\/strong>) from iOS 15 to <strong>iOS 16<\/strong>.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\"><br>If you are using an <strong>iPhone 7 or an older generation<\/strong> device, your phone <strong>is not compatible with iOS 16 <\/strong>and will no longer receive new Clockify app updates. You can still access the app but it will remain on <strong>Clockify v2.16.15<\/strong>, and you can continue tracking your time there without interruption.<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Iniciar sess\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para usar o aplicativo Clockify, primeiro voc\u00ea precisa fazer login na sua conta:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Digite o e-mail da sua conta Clockify<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Continuar com e-mail<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Ou escolha <strong>Continuar com o Google<\/strong> se voc\u00ea associou sua conta Clockify \u00e0 sua conta do Google<\/li>\n\n\n\n<li class=\"translation-block\">Ou escolha <strong>Continuar com a Apple<\/strong> e insira sua AppleID&nbsp;<\/li>\n\n\n\n<li class=\"translation-block\">Ou selecione <strong>Continuar com a Microsoft<\/strong> e insira seu nome de usu\u00e1rio e senha<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/iOS-login-with-microsoft-576x1024.jpg\" alt=\"\" class=\"wp-image-29878\" style=\"aspect-ratio:0.5625112107623318;width:291px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/iOS-login-with-microsoft-576x1024.jpg 576w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/iOS-login-with-microsoft-169x300.jpg 169w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/iOS-login-with-microsoft-7x12.jpg 7w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/iOS-login-with-microsoft.jpg 750w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Escolha a regi\u00e3o se quiser hospedar dados em um dos <a href=\"https:\/\/clockify.me\/help\/pt\/getting-started\/data-regions\">servidores regionais<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea receber\u00e1 um e-mail com um c\u00f3digo de verifica\u00e7\u00e3o e um link para verificar seu endere\u00e7o de e-mail.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para prosseguir:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Insira o c\u00f3digo de verifica\u00e7\u00e3o na tela de verifica\u00e7\u00e3o<\/li>\n\n\n\n<li>Ou toque no link e fa\u00e7a login automaticamente<\/li>\n<\/ol>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Ap\u00f3s a verifica\u00e7\u00e3o bem-sucedida, voc\u00ea ser\u00e1 redirecionado para a tela do <strong>Rastreamento de tempo<\/strong> e poder\u00e1 come\u00e7ar a monitorar o tempo.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Se voc\u00ea ainda n\u00e3o tem uma conta Clockify, voc\u00ea pode criar uma tocando no bot\u00e3o <strong>Inscrever-se<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Login com dom\u00ednio personalizado ou um subdom\u00ednio<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea estiver em um dom\u00ednio ou subdom\u00ednio personalizado, tamb\u00e9m poder\u00e1 usar o aplicativo Clockify iOS.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para fazer login:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Abra o aplicativo e insira o e-mail da sua conta Clockify<\/li>\n\n\n\n<li class=\"translation-block\">Escolha o espa\u00e7o de trabalho associado ao seu subdom\u00ednio\/dom\u00ednio personalizado <\/li>\n\n\n\n<li>Voc\u00ea ser\u00e1 redirecionado automaticamente para o subdom\u00ednio\/dom\u00ednio personalizado em quest\u00e3o<br><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"541\" class=\"wp-image-21992\" style=\"width: 250px;\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002.png\" alt=\"\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002.png 1170w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002-139x300.png 139w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002-473x1024.png 473w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002-768x1662.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002-710x1536.png 710w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002-946x2048.png 946w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/IMG_0002-6x12.png 6w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Continuar com e-mail<\/strong><\/li>\n\n\n\n<li>Voc\u00ea receber\u00e1 um e-mail com um c\u00f3digo de verifica\u00e7\u00e3o<\/li>\n\n\n\n<li>Siga as instru\u00e7\u00f5es para validar seu e-mail inserindo o c\u00f3digo<\/li>\n<\/ol>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Ap\u00f3s a verifica\u00e7\u00e3o bem-sucedida, voc\u00ea ser\u00e1 redirecionado para sua conta Clockify e para a tela do <strong>Rastreador de tempo<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Iniciar sess\u00e3o com login da Apple<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Se ao fazer login voc\u00ea escolher a op\u00e7\u00e3o <strong>Continuar com a Apple<\/strong>:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Insira sua Apple ID<\/li>\n\n\n\n<li>Depois que seu ID for verificado, voc\u00ea poder\u00e1 <strong>Crie  sua conta<\/strong>&nbsp;<\/li>\n\n\n\n<li>O processo de login ser\u00e1 feito via  Google ou Apple<\/li>\n\n\n\n<li>Ap\u00f3s concluir o processo, aparecer\u00e1 a  tela de inscri\u00e7\u00e3o&nbsp;<\/li>\n\n\n\n<li class=\"translation-block\">Verifique os <strong>Termos e Condi\u00e7\u00f5es da CAKE.com<\/strong>&nbsp;<\/li>\n\n\n\n<li>Crie  sua conta<\/li>\n<\/ol>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea ser\u00e1 redirecionado para a tela <strong>Rastreador de tempo<\/strong> e poder\u00e1 come\u00e7ar a monitorar o tempo imediatamente.<\/p>\n\n\n\n<p class=\"note wp-block-paragraph\">&nbsp;Se voc\u00ea estiver fazendo login via Google ou Apple, n\u00e3o haver\u00e1 a etapa de verifica\u00e7\u00e3o da conta.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Depois de fazer login, voc\u00ea chegar\u00e1 \u00e0 tela de Rastreador de tempo, onde ver\u00e1 suas entradas mais recentes. Navegue pelo menu do aplicativo tocando no \u00edcone de hamb\u00farguer na parte superior esquerda da tela do <strong>Rastreador de tempo<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"481\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/image-2.png\" alt=\"\" class=\"wp-image-19879\" style=\"width:254px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/image-2.png 481w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/image-2-141x300.png 141w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/image-2-6x12.png 6w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph\"><br>Se voc\u00ea for membro de v\u00e1rios espa\u00e7os de trabalho, poder\u00e1 ver a lista de todos os seus espa\u00e7os de trabalho e suas <a href=\"https:\/\/clockify.me\/help\/pt\/getting-started\/data-regions\">regi\u00f5es de hospedagem<\/a> (se hospedado em servidores regionais diferentes). Toque no seu espa\u00e7o de trabalho atual para expandir o menu e alternar entre os espa\u00e7os de trabalho.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"500\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-15.58.34.png\" alt=\"\" class=\"wp-image-19881\" style=\"width:255px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-15.58.34.png 432w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-15.58.34-259x300.png 259w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-15.58.34-10x12.png 10w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/figure>\n\n\n\n<p class=\"note wp-block-paragraph\">O login manual est\u00e1 desabilitado para iOS v2.14.5 e superior. Usu\u00e1rios com essas vers\u00f5es ou superiores n\u00e3o ter\u00e3o mais a op\u00e7\u00e3o de login manual, enquanto usu\u00e1rios com vers\u00f5es mais antigas ainda poder\u00e3o fazer login manualmente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Novidades<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Ao iniciar a tela pela primeira vez, ap\u00f3s cada nova atualiza\u00e7\u00e3o, uma tela <strong>Novidades<\/strong> aparece detalhando todas as altera\u00e7\u00f5es.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"626\" height=\"790\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-11.02.06.png\" alt=\"\" class=\"wp-image-25673\" style=\"width:220px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-11.02.06.png 626w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-11.02.06-238x300.png 238w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-11.02.06-10x12.png 10w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Depois de revisar todos os novos recursos, toque em <strong>Explorar Clockify<\/strong> para acessar o aplicativo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rastreador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A tela do Rastreador exibe uma lista das 50 entradas de tempo mais recentes. Aqui voc\u00ea pode:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\"><strong>Alternar entre o tempo de rastreamento e o modo de pausa<\/strong>: deslize para a esquerda<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Criar uma nova entrada de tempo<\/strong>: toque no reproduzir azul (Cron\u00f4metro) <\/li>\n\n\n\n<li class=\"translation-block\"><strong>Adicionar tempo manualmente<\/strong>: toque no bot\u00e3o + no canto superior direito<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Continuar rastreando<\/strong> <strong> o tempo de uma tarefa recente<\/strong>: deslize para a direita em uma entrada de tempo<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Excluir uma entrada de tempo<\/strong>: deslize para a esquerda em uma entrada de tempo<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Ver o cron\u00f4metro correndo<\/strong> na parte inferior, se estiver funcionando<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Editar entradas de tempo<\/strong>: toque em uma entrada de tempo ou no cron\u00f4metro em execu\u00e7\u00e3o para editar<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Ver entradas anteriores<\/strong>: deslize para cima a partir do meio da tela<\/li>\n<\/ul>\n\n\n\n<p class=\"tip wp-block-paragraph\">Quando voc\u00ea cria manualmente uma entrada de tempo, os hor\u00e1rios de in\u00edcio e t\u00e9rmino padr\u00e3o s\u00e3o fornecidos automaticamente, para que voc\u00ea n\u00e3o precise inseri-los toda vez. No entanto, voc\u00ea pode ajustar facilmente esses hor\u00e1rios inserindo seus hor\u00e1rios de in\u00edcio e t\u00e9rmino preferidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Clockify faz uma sincroniza\u00e7\u00e3o autom\u00e1tica toda vez que voc\u00ea executa uma a\u00e7\u00e3o. Se voc\u00ea estiver desconectado, o Clockify sincronizar\u00e1 assim que voc\u00ea se conectar. Se voc\u00ea n\u00e3o fizer nada, ter\u00e1 que fazer uma sincroniza\u00e7\u00e3o manual, deslizando do centro da tela para baixo.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Clockify agrupa entradas de tempo semelhantes em uma entrada expans\u00edvel. Se desejar ver as entradas em ordem cronol\u00f3gica, v\u00e1 para <strong>Configura\u00e7\u00f5es do perfil<\/strong> &gt; <strong>Prefer\u00eancias<\/strong> no aplicativo da web e desative <strong>Agrupar entradas de tempo semelhante<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.09.29-1-470x1024.png\" alt=\"\" class=\"wp-image-23685\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.09.29-1-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.09.29-1-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.09.29-1-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.09.29-1.png 704w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><figcaption class=\"wp-element-caption\">Iniciar cron\u00f4metro<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.11.19-1-472x1024.png\" alt=\"\" class=\"wp-image-23687\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.11.19-1-472x1024.png 472w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.11.19-1-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.11.19-1-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.11.19-1.png 706w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><figcaption class=\"wp-element-caption\">Adicionar tempo (modo manual)<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.12.56-1-473x1024.png\" alt=\"\" class=\"wp-image-23688\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.12.56-1-473x1024.png 473w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.12.56-1-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.12.56-1-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.12.56-1.png 708w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><figcaption class=\"wp-element-caption\">Adicionar tempo (modo manual)<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Criar uma entrada de tempo<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Selecione o modo de entrada de tempo<\/li>\n\n\n\n<li>Clique no \u00edcone reprodu\u00e7\u00e3o\/mais no canto inferior esquerdo para come\u00e7ar a trabalhar<\/li>\n\n\n\n<li>Adicione detalhes (descri\u00e7\u00e3o, hora de in\u00edcio\/t\u00e9rmino, projeto, tarefa, faturabilidade, etiquetas)<\/li>\n\n\n\n<li>Se estiver no modo cron\u00f4metro, pare o cron\u00f4metro quando terminar de trabalhar<\/li>\n<\/ol>\n\n\n\n<p class=\"translation-block wp-block-paragraph\"><strong>Continue o cron\u00f4metro<\/strong> para uma entrada de tempo existente deslizando para a direita na entrada de tempo e tocando em Continuar. Em seguida, uma nova entrada de tempo com a mesma descri\u00e7\u00e3o, projeto, cliente e etiqueta ser\u00e1 criada e o cron\u00f4metro come\u00e7ar\u00e1 a contar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Calend\u00e1rio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode ver todas as suas entradas de tempo em uma exibi\u00e7\u00e3o de calend\u00e1rio (dispon\u00edvel na barra lateral). <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Toque em uma entrada de tempo para edit\u00e1-la ou continue o cron\u00f4metro nela<\/li>\n\n\n\n<li>Adicione uma nova entrada pressionando em + no canto \n<ul class=\"wp-block-list\">\n<li class=\"translation-block\">Ou pressione e segure o intervalo de tempo desejado at\u00e9 que o formul\u00e1rio <strong>Nova entrada de tempo<\/strong> apare\u00e7a<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Para mover a entrada de tempo, pressione e segure um intervalo de tempo e arraste e solte-o no hor\u00e1rio desejado <\/li>\n\n\n\n<li>Navegue para outros dias tocando em uma data<\/li>\n\n\n\n<li>Veja quando voc\u00ea tem folga <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Sincronize o Clockify com o seu calend\u00e1rio local<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Conecte o calend\u00e1rio do seu telefone para rastrear e ver eventos no Clockify. <\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">V\u00e1 para  <strong>Configura\u00e7\u00f5es<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Integra\u00e7\u00e3o de Calend\u00e1rio<\/strong><\/li>\n\n\n\n<li>Alterne o interruptor para se conectar com o seu calend\u00e1rio<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>OK <\/strong>na tela de de confirma\u00e7\u00e3o que aparece para permitir que o Clockify acesse seu calend\u00e1rio<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea receber\u00e1 uma lista de todas as contas e calend\u00e1rios conectados ao seu telefone. Escolha quais eventos voc\u00ea gostaria de ver em seu calend\u00e1rio (por exemplo, tarefa\/projeto\/tarefa agendada, feriados, contatos) ou habilite todos eles.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"897\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-16.07.26-897x1024.png\" alt=\"\" class=\"wp-image-19884\" style=\"width:274px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-16.07.26-897x1024.png 897w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-16.07.26-263x300.png 263w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-16.07.26-768x877.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-16.07.26-11x12.png 11w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-16.07.26.png 1168w\" sizes=\"auto, (max-width: 897px) 100vw, 897px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, ao acessar o Calend\u00e1rio, voc\u00ea poder\u00e1 visualizar os seus eventos<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Rastreie o tempo com os eventos de calend\u00e1rio<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ao tocar em um dos eventos na tela do Calend\u00e1rio, voc\u00ea obter\u00e1 a planilha de a\u00e7\u00f5es com a op\u00e7\u00e3o para:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Iniciar cron\u00f4metro <\/li>\n\n\n\n<li>Copiar como entrada de tempo (n\u00e3o dispon\u00edvel se For\u00e7ar cron\u00f4metro estiver ativado)<\/li>\n\n\n\n<li>Cancelar a\u00e7\u00e3o<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/calendar_integration_track_time-473x1024.png\" alt=\"\" class=\"wp-image-19886\" style=\"width:250px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/calendar_integration_track_time-473x1024.png 473w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/calendar_integration_track_time-139x300.png 139w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/calendar_integration_track_time-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/calendar_integration_track_time.png 614w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Se voc\u00ea escolher a op\u00e7\u00e3o <strong>Iniciar cron\u00f4metro<\/strong>,  voc\u00ea iniciar\u00e1 o cron\u00f4metro para o evento escolhido. Voc\u00ea pode descartar o cron\u00f4metro de execu\u00e7\u00e3o na tela do  <strong>Rastreador <\/strong>. <br>Com <strong>Copiar como entrada de tempo<\/strong>,  voc\u00ea copiar\u00e1 o evento como uma entrada de tempo que pode ser adicionada a um projeto ou tarefa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se houver um evento rec\u00e9m-criado em seu calend\u00e1rio, v\u00e1 para a tela Calend\u00e1rio e aguarde a sincroniza\u00e7\u00e3o dos eventos. Ap\u00f3s a conclus\u00e3o da sincroniza\u00e7\u00e3o, voc\u00ea poder\u00e1 v\u00ea-los no Clockify.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Temporizador Pomodoro<\/h2>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">O <strong> cron\u00f4metro Pomodoro<\/strong> ajuda voc\u00ea a estruturar seu trabalho dividindo-o em sess\u00f5es de trabalho cronometrado e intervalos, permitindo que voc\u00ea mantenha o foco e evite o esgotamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como funciona<\/strong><\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Uma sess\u00e3o Pomodoro consiste em uma <strong>sess\u00e3o de foco<\/strong> (tempo de trabalho) e uma <strong>sess\u00e3o de intervalo<\/strong> (pausa).<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea pode iniciar um cron\u00f4metro para uma sess\u00e3o de concentra\u00e7\u00e3o para come\u00e7ar seu trabalho.&nbsp;<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Para iniciar o cron\u00f4metro <strong>Pomodoro<\/strong>:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Acesse a p\u00e1gina Rastreador<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Pomodoro<\/strong> para alternar para a aba <strong>Pomodoro<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">A partir daqui, toque em <strong>Iniciar sess\u00e3o<\/strong> para iniciar a sess\u00e3o imediatamente<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"538\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.59.26-538x1024.png\" alt=\"\" class=\"wp-image-26277\" style=\"width:300px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.59.26-538x1024.png 538w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.59.26-158x300.png 158w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.59.26-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.59.26.png 570w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea ser\u00e1 solicitado a editar os detalhes do foco, incluindo a adi\u00e7\u00e3o do projeto e alguns detalhes opcionais (descri\u00e7\u00e3o, tarefa, tag, faturabilidade, meio per\u00edodo).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"574\" height=\"734\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.58.02.png\" alt=\"\" class=\"wp-image-26276\" style=\"width:300px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.58.02.png 574w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.58.02-235x300.png 235w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.58.02-9x12.png 9w\" sizes=\"auto, (max-width: 574px) 100vw, 574px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Assim que a sess\u00e3o de foco terminar, um novo cron\u00f4metro para uma pausa pode ser iniciado automaticamente, ou voc\u00ea pode inici\u00e1-lo manualmente.<br>Quando o intervalo terminar, o cron\u00f4metro parar\u00e1 e voc\u00ea poder\u00e1 continuar seu trabalho ou iniciar uma nova tarefa.<\/p>\n\n\n\n<p class=\"tip wp-block-paragraph\">O valor m\u00ednimo para sess\u00f5es de foco e pausa \u00e9 de um minuto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Personalize suas sess\u00f5es<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode configurar as configura\u00e7\u00f5es do Cron\u00f4metro Pomodoro para corresponder \u00e0s suas prefer\u00eancias.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"543\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.01.27-543x1024.png\" alt=\"\" class=\"wp-image-26278\" style=\"width:300px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.01.27-543x1024.png 543w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.01.27-159x300.png 159w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.01.27-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.01.27.png 572w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"894\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.02.26-894x1024.png\" alt=\"\" class=\"wp-image-26279\" style=\"width:300px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.02.26-894x1024.png 894w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.02.26-262x300.png 262w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.02.26-768x880.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.02.26-10x12.png 10w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-11.02.26.png 1070w\" sizes=\"auto, (max-width: 894px) 100vw, 894px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\"><strong>Defina intervalos<\/strong> para suas sess\u00f5es de foco e pausa <\/li>\n\n\n\n<li class=\"translation-block\"><strong>Ative os intervalos autom\u00e1ticos<\/strong> para iniciar um cron\u00f4metro de intervalo assim que sua sess\u00e3o de trabalho terminar <\/li>\n\n\n\n<li class=\"translation-block\"><strong>Escolha um projeto padr\u00e3o<\/strong> para suas pausas Pomodoro <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Notifica\u00e7\u00f5es<\/strong><\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea receber\u00e1 notifica\u00e7\u00f5es push quando for a hora de iniciar ou encerrar uma sess\u00e3o, para n\u00e3o precisar ficar de olho no aplicativo. Voc\u00ea pode at\u00e9 iniciar um intervalo diretamente na notifica\u00e7\u00e3o tocando em <strong>Iniciar intervalo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Widget de Cron\u00f4metro<\/h2>\n\n\n\n<p class=\"note translation-block wp-block-paragraph\">O suporte para widgets legados foi descontinuado no <strong>iOS 18 e vers\u00f5es posteriores<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode iniciar e parar rapidamente o cron\u00f4metro do seu telefone sem precisar abrir o aplicativo.&nbsp;<span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;It would make switching time between tasks way easier. It would work by having your projects in the box that is given to each app in widgets. And like the tag line on the iOS store. \u201cTrack time with one tap\u201d. So just clicking on the project would start adding time to it, and switching projects would be as simple as clicking another project.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:256,&quot;11&quot;:4}\" data-sheets-ischild=\"\">O widget facilita a troca de tempo entre as tarefas para que voc\u00ea possa acompanhar o tempo com um \u00fanico toque. Basta clicar no projeto para adicionar o tempo a ele e alterar os projetos clicando em outro projeto.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tamb\u00e9m pode iniciar\/parar o \u00faltimo cron\u00f4metro com <strong>toque h\u00e1ptico<\/strong> (toque 3D) ao pressionar e segurar o \u00edcone do aplicativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Como adicionar um widget \u00e0 sua tela inicial:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>V\u00e1 para a tela de widgets no seu iOS (tela \u00e0 esquerda da tela inicial)<\/li>\n\n\n\n<li class=\"translation-block\">V\u00e1 para a parte inferior da tela e toque em <strong>Editar<\/strong><\/li>\n\n\n\n<li>Role para baixo at\u00e9 <strong>Personalizar <\/strong>e ative o widget Clockify<\/li>\n\n\n\n<li>Aperte o bot\u00e3o reproduzir e inicie um novo cron\u00f4metro<\/li>\n\n\n\n<li>Toque em uma seta para ver as atividades anteriores, para que voc\u00ea possa continuar rapidamente um cron\u00f4metro anterior<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"750\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.03.40.png\" alt=\"\" class=\"wp-image-19856\" style=\"width:291px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.03.40.png 612w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.03.40-245x300.png 245w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.03.40-10x12.png 10w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Modo de Planilha<\/h2>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea pode registrar quanto tempo gastou em projetos para cada dia da semana na Planilha de horas (<a href=\"https:\/\/clockify.me\/help\/pt\/track-time-and-expenses\/timesheet-view\" target=\"_blank\" rel=\"noreferrer noopener\">Planilha de horas<\/a> precisa ser habilitada nas configura\u00e7\u00f5es do espa\u00e7o de trabalho primeiro).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Crie o modelo da seguinte maneira:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Adicione um projeto\/tarefa<\/li>\n\n\n\n<li>Pressione no campo ao lado do projeto adicionado para o dia em que deseja registrar o tempo<\/li>\n\n\n\n<li>Digite o tempo<\/li>\n\n\n\n<li>Quando uma nova semana come\u00e7ar, voc\u00ea pode reutilizar a combina\u00e7\u00e3o de projeto\/tarefa da semana passada ou usar um modelo<\/li>\n<\/ol>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.07.54-474x1024.png\" alt=\"\" class=\"wp-image-19857\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.07.54-474x1024.png 474w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.07.54-139x300.png 139w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.07.54-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.07.54.png 616w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption class=\"wp-element-caption\">Inserir o tempo na planilha de horas<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.27-471x1024.png\" alt=\"\" class=\"wp-image-19858\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.27-471x1024.png 471w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.27-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.27-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.27.png 612w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><figcaption class=\"wp-element-caption\">Selecionar tarefa\/projeto<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.58-473x1024.png\" alt=\"\" class=\"wp-image-19859\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.58-473x1024.png 473w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.58-139x300.png 139w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.58-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.08.58.png 612w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><figcaption class=\"wp-element-caption\">Atividades semanais de preenchimento autom\u00e1tico<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"tip translation-block wp-block-paragraph\">Dependendo do per\u00edodo de aprova\u00e7\u00e3o definido nas <strong>configura\u00e7\u00f5es do espa\u00e7o de trabalho<\/strong>, podem ser criados modelos de Planilha de horas para per\u00edodos semanais, semestrais e mensais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Modelo de planilha de horas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea estiver trabalhando em um projeto complexo que dura muito tempo e muitas vezes precisa inserir as mesmas entradas de hor\u00e1rio em sua  planilha de horas, voc\u00ea pode configurar um modelo para economizar tempo e reutiliz\u00e1-lo sempre que precisar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para definir a planilha de horas como modelo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Abra a tela <strong>Planilha de horas<\/strong> no aplicativo<\/li>\n\n\n\n<li>Abaixo da lista de entradas rastreadas, voc\u00ea ter\u00e1 as seguintes op\u00e7\u00f5es:\n<ul class=\"wp-block-list\">\n<li><strong>Enviar para aprova\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li class=\"translation-block\"><strong>Criar<\/strong>\/<strong>Aplicar modelo<\/strong><br>ou<\/li>\n\n\n\n<li><strong>Copiar a semana anterior<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"900\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-01-17-at-10.20.28.png\" alt=\"\" class=\"wp-image-21839\" style=\"width:300px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-01-17-at-10.20.28.png 828w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-01-17-at-10.20.28-276x300.png 276w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-01-17-at-10.20.28-768x835.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-01-17-at-10.20.28-11x12.png 11w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Se voc\u00ea escolher <strong>Aplicar modelo<\/strong>, ser\u00e1 exibida uma lista de modelos dispon\u00edveis. Os modelos s\u00e3o extra\u00eddos de entradas anteriores.<\/p>\n\n\n\n<p class=\"tip wp-block-paragraph\">Se voc\u00ea aplicar um modelo que inclua projetos ou tarefas que foram exclu\u00eddos, arquivados ou que n\u00e3o est\u00e3o mais acess\u00edveis para voc\u00ea, esses itens n\u00e3o ser\u00e3o adicionados a sua Planilha de horas atual.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Copiar a semana anterior<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Para copiar as tarefas e projetos da semana passada para a semana atual, toque no bot\u00e3o <strong>Copiar a semana anterior<\/strong> bot\u00e3o localizado abaixo do prompt da planilha de horas, onde as entradas da semana atual normalmente s\u00e3o exibidas.<\/p>\n\n\n\n<p class=\"note wp-block-paragraph\">Esta op\u00e7\u00e3o aparecer\u00e1 se voc\u00ea n\u00e3o tiver entradas para a semana atual. Se voc\u00ea j\u00e1 adicionou entradas, a op\u00e7\u00e3o n\u00e3o estar\u00e1 vis\u00edvel.<\/p>\n\n\n\n<div class=\"wp-block-custom-highlight-box custom-box color-blue\"><div class=\"box-header\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask0_1_85240\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_1_85240)\"><path d=\"M8.275 7.72461L5.275 4.72461L6.7 3.29961L9.7 6.29961L8.275 7.72461ZM12 5.34961V1.09961H14V5.34961H12ZM19.275 18.7246L16.275 15.7246L17.7 14.2996L20.7 17.2996L19.275 18.7246ZM17.7 7.72461L16.275 6.29961L19.275 3.29961L20.7 4.72461L17.7 7.72461ZM18.65 11.9996V9.99961H22.9V11.9996H18.65ZM5.125 21.6996L2.3 18.8746C2.1 18.6746 2 18.4413 2 18.1746C2 17.9079 2.1 17.6746 2.3 17.4746L11.375 8.37461C11.9583 7.79128 12.6667 7.49961 13.5 7.49961C14.3333 7.49961 15.0417 7.79128 15.625 8.37461C16.2083 8.95794 16.5 9.66628 16.5 10.4996C16.5 11.3329 16.2083 12.0413 15.625 12.6246L6.525 21.6996C6.325 21.8996 6.09167 21.9996 5.825 21.9996C5.55833 21.9996 5.325 21.8996 5.125 21.6996ZM5.825 19.5996L12.1 13.3246L10.675 11.9246L4.425 18.1746L5.825 19.5996Z\" fill=\"#03A9F4\"><\/path><\/g><\/svg><span class=\"box-label\">Dica<\/span><\/div><div class=\"box-content\">\n<p class=\"wp-block-paragraph\">Se estiver off-line, voc\u00ea ainda poder\u00e1 salvar um modelo. Quando estiver on-line novamente, voc\u00ea poder\u00e1 aplicar o modelo salvo.<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Editar entrada<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para editar uma entrada de tempo, toque na tela do Rastreador. Se o cron\u00f4metro estiver em execu\u00e7\u00e3o, voc\u00ea poder\u00e1 editar os detalhes dessa entrada tocando no cron\u00f4metro.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Na tela <strong>Editar detalhes da entrada<\/strong> voc\u00ea pode:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Editar a hora de in\u00edcio e t\u00e9rmino, bem como a data<\/li>\n\n\n\n<li>Selecionar tarefa e projeto (al\u00e9m de criar projetos, tarefas e clientes do aplicativo)<\/li>\n\n\n\n<li>Editar a descri\u00e7\u00e3o do tempo<\/li>\n\n\n\n<li>Marcar o registro como fatur\u00e1vel<\/li>\n\n\n\n<li>Adicionar\/remover etiquetas (e tamb\u00e9m cri\u00e1-las)<\/li>\n<\/ul>\n\n\n\n<p class=\"tip translation-block wp-block-paragraph\">Membros regulares (n\u00e3o administradores) da equipe n\u00e3o poder\u00e3o criar clientes, projetos e tags se n\u00e3o tiverem essas permiss\u00f5es. Para conceder essas permiss\u00f5es, voc\u00ea precisar\u00e1 fazer login pelo navegador da web e definir <strong>Quem pode criar projetos e clientes<\/strong>, <strong>Quem pode criar tarefas<\/strong> e <strong>Quem pode criar tags<\/strong> como <strong>Qualquer pessoa<\/strong> nas configura\u00e7\u00f5es do espa\u00e7o de trabalho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada vez que voc\u00ea edita algo, o Clockify salva as altera\u00e7\u00f5es e sincroniza os dados automaticamente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dividir registro de tempo<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Ao controlar o tempo pelo Clockify em um celular, voc\u00ea pode dividir uma entrada em segmentos menores nas p\u00e1ginas <strong>Controlador de tempo<\/strong> e <strong>Calend\u00e1rio<\/strong> e controlar o tempo com mais precis\u00e3o e flexibilidade.&nbsp;<\/p>\n\n\n\n<p class=\"tip translation-block wp-block-paragraph\">Este recurso est\u00e1 dispon\u00edvel para todos os usu\u00e1rios em um <a href=\"https:\/\/clockify.me\/help\/pt\/administration\/subscription-plans#basic\">plano pago<\/a> e <a href=\"https:\/\/clockify.me\/help\/pt\/administration\/free-trial\">teste gratuito<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Como funciona<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Encontre a entrada que deseja dividir na p\u00e1gina <strong>Rastreador de tempo<\/strong> ou <strong>Calend\u00e1rio<\/strong><\/li>\n\n\n\n<li>Escolha a op\u00e7\u00e3o de dividir a entrada<br><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"559\" class=\"wp-image-26271\" style=\"width: 300px;\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.41.21.png\" alt=\"\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.41.21.png 572w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.41.21-161x300.png 161w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.41.21-549x1024.png 549w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-09-23-at-10.41.21-6x12.png 6w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li>\n\n\n\n<li>Escolha o hor\u00e1rio em que deseja dividir a entrada<\/li>\n<\/ol>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Quando voc\u00ea divide uma entrada em execu\u00e7\u00e3o, a primeira entrada para no ponto escolhido e uma nova come\u00e7a a partir desse exato momento, continuando a ser executada.<br>Se voc\u00ea usar um controle deslizante de linha do tempo, a dura\u00e7\u00e3o de ambas as entradas ser\u00e1 ajustada dinamicamente conforme voc\u00ea as arrasta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"392\" height=\"362\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image.png\" alt=\"\" class=\"wp-image-26266\" style=\"width:300px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image.png 392w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-300x277.png 300w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-13x12.png 13w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/figure>\n\n\n\n<p class=\"note wp-block-paragraph\">Entradas de tempo com menos de 2 minutos de dura\u00e7\u00e3o n\u00e3o podem ser divididas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Excluir entrada<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Para excluir uma entrada, volte para a tela do <strong>Rastreador de Tempo<\/strong>, deslize para a esquerda na entrada de tempo e toque em <strong>Excluir<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.38.15-471x1024.png\" alt=\"\" class=\"wp-image-23676\" style=\"width:270px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.38.15-471x1024.png 471w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.38.15-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.38.15-706x1536.png 706w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.38.15-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.38.15.png 712w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.39.24-470x1024.png\" alt=\"\" class=\"wp-image-23677\" style=\"width:270px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.39.24-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.39.24-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.39.24-704x1536.png 704w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.39.24-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.39.24.png 708w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tamb\u00e9m pode excluir entradas agrupadas da mesma maneira.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"468\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-10.47.09.png\" alt=\"\" class=\"wp-image-25670\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-10.47.09.png 646w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-10.47.09-300x217.png 300w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-08-20-at-10.47.09-18x12.png 18w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/figure>\n\n\n\n<p class=\"tip translation-block wp-block-paragraph\">Se quiser ver entradas semelhantes agrupadas, v\u00e1 para a aba <strong>Prefer\u00eancias<\/strong> &gt; <strong>Geral<\/strong> no aplicativo web e ative <strong>Agrupar entradas semelhantes<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Desfazer a\u00e7\u00e3o \u2018excluir\u2019<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Se voc\u00ea estiver em um <strong>Rastreador de Tempo<\/strong>, <strong>Planilha de horas<\/strong>, <strong>Calend\u00e1rio<\/strong> ou <strong>Despesas<\/strong>, poder\u00e1 recuperar as entradas exclu\u00eddas. Com a a\u00e7\u00e3o de desfazer \"excluir\", voc\u00ea pode reverter rapidamente a\u00e7\u00f5es como excluir entradas ou despesas e descartar um cron\u00f4metro em execu\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ferramenta est\u00e1 dispon\u00edvel para todos os usu\u00e1rios, independentemente do plano ou fun\u00e7\u00e3o. Voc\u00ea pode us\u00e1-lo independentemente de estar em um plano de teste ou pago.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Desfazer entradas exclu\u00eddas<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Rastreador de tempo<\/strong>\n<ul class=\"wp-block-list\">\n<li>Deslize para a esquerda em uma entrada<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Excluir<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">A mensagem \u201cEntrada exclu\u00edda\u201d aparecer\u00e1 com a op\u00e7\u00e3o <strong>Desfazer<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Planilha de horas<\/strong>\n<ul class=\"wp-block-list\">\n<li>Toque em X no final da linha de entrada de tempo ou defina o tempo como 0 para exclu\u00ed-lo<\/li>\n\n\n\n<li>A mensagem pop-up mostrar\u00e1 \u201cEntrada exclu\u00edda\u201d<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Desfazer<\/strong> para trazer de volta a entrada<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Calend\u00e1rio<\/strong>\n<ul class=\"wp-block-list\">\n<li>Entrada de toque<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Excluir<\/strong><\/li>\n\n\n\n<li>A mensagem pop-up mostrar\u00e1 \u201cEntrada exclu\u00edda\u201d<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Desfazer<\/strong> para restaurar a entrada<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"779\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15-779x1024.jpeg\" alt=\"\" class=\"wp-image-22550\" style=\"width:260px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15-779x1024.jpeg 779w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15-228x300.jpeg 228w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15-768x1010.jpeg 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15-1168x1536.jpeg 1168w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15-9x12.jpeg 9w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.22.15.jpeg 1170w\" sizes=\"auto, (max-width: 779px) 100vw, 779px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"927\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.31.00-927x1024.png\" alt=\"\" class=\"wp-image-22554\" style=\"width:310px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.31.00-927x1024.png 927w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.31.00-272x300.png 272w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.31.00-768x848.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.31.00-11x12.png 11w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-04-07-at-10.31.00.png 1170w\" sizes=\"auto, (max-width: 927px) 100vw, 927px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Desfazer despesas exclu\u00eddas<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Despesas<\/strong>\n<ul class=\"wp-block-list\">\n<li>Delete uma despesa<\/li>\n\n\n\n<li>Aparece a mensagem \u201cDespesa apagada\u201d<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Desfazer<\/strong> para restaur\u00e1-lo<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"note wp-block-paragraph\">A mensagem sobre a a\u00e7\u00e3o de exclus\u00e3o permanece vis\u00edvel por 5 segundos. Se voc\u00ea mudar para outra tela, ela permanecer\u00e1 l\u00e1 at\u00e9 que voc\u00ea a descarte ou desapare\u00e7a ap\u00f3s 5 segundos.<\/p>\n\n\n\n<div class=\"wp-block-custom-highlight-box custom-box color-green\"><div class=\"box-header\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask-green\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask-green)\"><path d=\"M5 21.0001C4.45 21.0001 3.97917 20.8043 3.5875 20.4126C3.19583 20.0209 3 19.5501 3 19.0001V5.0001C3 4.4501 3.19583 3.97926 3.5875 3.5876C3.97917 3.19593 4.45 3.0001 5 3.0001H13.925L11.925 5.0001H5V19.0001H19V12.0501L21 10.0501V19.0001C21 19.5501 20.8042 20.0209 20.4125 20.4126C20.0208 20.8043 19.55 21.0001 19 21.0001H5ZM9 15.0001V10.7501L18.175 1.5751C18.375 1.3751 18.6 1.2251 18.85 1.1251C19.1 1.0251 19.35 0.975098 19.6 0.975098C19.8667 0.975098 20.1208 1.0251 20.3625 1.1251C20.6042 1.2251 20.825 1.3751 21.025 1.5751L22.425 3.0001C22.6083 3.2001 22.75 3.42093 22.85 3.6626C22.95 3.90426 23 4.1501 23 4.4001C23 4.6501 22.9542 4.89593 22.8625 5.1376C22.7708 5.37926 22.625 5.6001 22.425 5.8001L13.25 15.0001H9ZM11 13.0001H12.4L18.2 7.2001L17.5 6.5001L16.775 5.8001L11 11.5751V13.0001Z\" fill=\"#4CAF50\"><\/path><\/g><\/svg><span class=\"box-label\">Nota<\/span><\/div><div class=\"box-content\">\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea ainda pode usar <strong>Desfazer<\/strong> quando estiver offline, mas apenas para entradas que foram criadas offline. Se voc\u00ea tentar desfazer algo criado enquanto estiver online, a mensagem Desfazer desaparecer\u00e1 quando voc\u00ea ficar offline.<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Acompanhar intervalos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se quiser visualizar e otimizar quanto tempo voc\u00ea gasta nos intervalos, voc\u00ea pode acompanh\u00e1-los no Rastreador do seu dispositivo iOS.<\/p>\n\n\n\n<p class=\"note wp-block-paragraph\">O cron\u00f4metro de intervalo est\u00e1 dispon\u00edvel para todos os usu\u00e1rios, independentemente da sua fun\u00e7\u00e3o de usu\u00e1rio. Voc\u00ea s\u00f3 precisa ativar os intervalos nas configura\u00e7\u00f5es do espa\u00e7o de trabalho do aplicativo da web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para iniciar um intervalo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Toque na seta e mude para o <strong>Modo de Cron\u00f4metro<\/strong> na tela do <strong>Rastreador<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Navegue at\u00e9 o bot\u00e3o <strong>reproduzir<\/strong> no canto inferior direito e deslize para a esquerda<br><img loading=\"lazy\" width=\"250\" height=\"118\" class=\"wp-image-23693\" style=\"width: 250px\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.50.png\" alt=\"\" \/><\/li>\n\n\n\n<li class=\"translation-block\">O bot\u00e3o de intervalo (\u00edcone de x\u00edcara) aparece, agora voc\u00ea est\u00e1 no <strong>modo de intervalo<\/strong> <\/li>\n\n\n\n<li class=\"translation-block\">Comece o intervalo tocando no bot\u00e3o<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Cada entrada de intervalo cont\u00e9m o mesmo tipo de informa\u00e7\u00e3o que qualquer entrada de tempo, incluindo tempo de in\u00edcio e t\u00e9rmino, dura\u00e7\u00e3o, nome do projeto, se \u00e9 fatur\u00e1vel ou n\u00e3o e, opcionalmente, alguns campos personalizados.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.01-470x1024.png\" alt=\"\" class=\"wp-image-23694\" style=\"width:293px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.01-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.01-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.01-705x1536.png 705w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.01-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.36.01.png 708w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea sempre pode editar e excluir entradas de intervalo, a menos que esse per\u00edodo esteja bloqueado e as entradas de tempo sejam aprovadas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Importante:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se o rastreamento de intervalos estiver desabilitado ou o espa\u00e7o de trabalho sofrer rebaixamento , as entradas de intervalo rastreadas permanecer\u00e3o no Rastreador<\/li>\n\n\n\n<li>Se For\u00e7ar Cron\u00f4metro estiver ativado, voc\u00ea n\u00e3o poder\u00e1 alternar o modo e s\u00f3 poder\u00e1 iniciar o cron\u00f4metro tocando em reproduzir&nbsp;<\/li>\n\n\n\n<li>Se o Modo de intervalo estiver ativado, quando voc\u00ea duplicar ou continuar a entrada de intervalo, uma nova entrada ser\u00e1 criada&nbsp;<\/li>\n\n\n\n<li>Se o Modo de intervalo estiver desativado, quando voc\u00ea duplicar ou continuar a entrada de intervalo, uma entrada regular ser\u00e1 criada<\/li>\n\n\n\n<li>O cron\u00f4metro de intervalo est\u00e1 dispon\u00edvel no modo offline<\/li>\n\n\n\n<li>O formato de dura\u00e7\u00e3o definido nas configura\u00e7\u00f5es do espa\u00e7o de trabalho, no aplicativo da web, ser\u00e1 aplicado&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Rastreamento de feriados e folgas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O Clockify permite que voc\u00ea acompanhe e gerencie os registros de folga e f\u00e9rias dos membros da sua equipe de trabalho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eles s\u00e3o exibidos distintamente em todas as p\u00e1ginas de rastreamento:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rastreador<\/li>\n\n\n\n<li>Planilha de horas<\/li>\n\n\n\n<li>Calend\u00e1rio<\/li>\n\n\n\n<li>Despesas<\/li>\n\n\n\n<li>Folgas:&nbsp;<\/li>\n\n\n\n<li>Relat\u00f3rios<\/li>\n<\/ul>\n\n\n\n<p class=\"note wp-block-paragraph\">Os registros de f\u00e9rias e feriados podem ser criados por propriet\u00e1rios e administradores.&nbsp;<\/p>\n\n\n\n<p class=\"tip translation-block wp-block-paragraph\">Para usar a tela <strong>Folgas<\/strong> do iOS, o recurso precisa primeiro ser ativado nas <a href=\"https:\/\/clockify.me\/help\/pt\/track-time-and-expenses\/workspaces#workspace-settings\">Configura\u00e7\u00f5es do espa\u00e7o de trabalho<\/a>, no aplicativo da web.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tempo fora da tela <\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Na tela <strong>Folgas<\/strong>, voc\u00ea pode gerenciar suas f\u00e9rias remuneradas e feriados. <br>Ela est\u00e1 organizada em tr\u00eas abas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\"><strong>Solicita\u00e7\u00f5es<\/strong>: Cont\u00e9m todas as solicita\u00e7\u00f5es enviadas e seus respectivos status (pendente, aprovada ou rejeitada) <\/li>\n\n\n\n<li class=\"translation-block\">Cronograma: Com uma vis\u00e3o geral de 30 dias de todas as folgas e feriados programados.<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Saldo<\/strong>: Usado para verificar seu saldo atual de dias de folga remunerada (acumulados, usados \u200b\u200be dispon\u00edveis), discriminado por pol\u00edtica.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"524\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38-524x1024.png\" alt=\"\" class=\"wp-image-27769\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38-524x1024.png 524w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38-153x300.png 153w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38-768x1501.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38-786x1536.png 786w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.12.38.png 844w\" sizes=\"auto, (max-width: 524px) 100vw, 524px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Enviar um pedido de folga<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para enviar uma solicita\u00e7\u00e3o de folga:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Abra a tela <strong>folga<\/strong> na barra lateral<\/li>\n\n\n\n<li class=\"translation-block\">Toque no bot\u00e3o <strong>+<\/strong> para criar uma nova solicita\u00e7\u00e3o.<\/li>\n\n\n\n<li>Selecione a pol\u00edtica de tempo (por exemplo, f\u00e9rias), o intervalo de datas e o per\u00edodo espec\u00edfico.<\/li>\n\n\n\n<li>Opcionalmente, adicione uma nota.<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Enviar<\/strong><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01-988x1024.png\" alt=\"\" class=\"wp-image-27770\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01-988x1024.png 988w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01-289x300.png 289w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01-768x796.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01-1482x1536.png 1482w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01-12x12.png 12w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.14.01.png 1748w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Ap\u00f3s a aprova\u00e7\u00e3o, voc\u00ea receber\u00e1 uma notifica\u00e7\u00e3o por e-mail e a solicita\u00e7\u00e3o ser\u00e1 atualizada para <strong>Aprovada<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gerenciar e aprovar solicita\u00e7\u00f5es<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As permiss\u00f5es para gerenciar a solicita\u00e7\u00e3o dependem da sua fun\u00e7\u00e3o: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\">Propriet\u00e1rios e administradores: Visualizem e gerenciem todas as solicita\u00e7\u00f5es.<\/li>\n\n\n\n<li class=\"translation-block\">Gerentes de Equipe: Gerenciam as solicita\u00e7\u00f5es dos membros de suas equipes.<\/li>\n\n\n\n<li class=\"translation-block\">Membros Espec\u00edficos: Gerenciar solicita\u00e7\u00f5es relacionadas \u00e0 pol\u00edtica espec\u00edfica de f\u00e9rias\/licen\u00e7a<\/li>\n<\/ul>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Para gerenciar uma solicita\u00e7\u00e3o, toque para abri-la, revise os detalhes e escolha <strong>Aprovar<\/strong>, <strong>Rejeitar<\/strong> ou <strong>Retirar<\/strong>.  <\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea s\u00f3 pode editar solicita\u00e7\u00f5es <strong>pendentes<\/strong>. Para isso, toque na solicita\u00e7\u00e3o em quest\u00e3o e fa\u00e7a as altera\u00e7\u00f5es necess\u00e1rias. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solicitar folga para outras pessoas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se um funcion\u00e1rio se esquecer de enviar uma solicita\u00e7\u00e3o, voc\u00ea, como propriet\u00e1rio\/administrador, pode fazer isso por ele: <\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Abra a tela <strong>Folga<\/strong> e toque em <strong>+<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Selecione o membro, a ap\u00f3lice e o per\u00edodo.<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Enviar<\/strong><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1003\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08-1003x1024.png\" alt=\"\" class=\"wp-image-27771\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08-1003x1024.png 1003w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08-294x300.png 294w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08-768x784.png 768w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08-1505x1536.png 1505w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08-12x12.png 12w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-11-27-at-11.15.08.png 1736w\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" \/><\/figure>\n\n\n\n<h3 id=\"filter-request\" class=\"wp-block-heading\">Solicita\u00e7\u00e3o de filtro<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Filtre solicita\u00e7\u00f5es por status ou membro da equipe seguindo estas etapas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Acesse a aba\u00a0<strong>Solicita\u00e7\u00f5es<\/strong><\/li>\n\n\n\n<li>Clique no \u00edcone de filtro e selecione op\u00e7\u00f5es como per\u00edodo de tempo, status da solicita\u00e7\u00e3o, membro espec\u00edfico ou equipe<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Suas prefer\u00eancias de filtragem ser\u00e3o salvas para visitas futuras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Submeter o tempo e as despesas para aprova\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se o seu espa\u00e7o de trabalho tiver a aprova\u00e7\u00e3o de tempo e despesas ativada, voc\u00ea poder\u00e1 enviar planilhas de horas semanais para aprova\u00e7\u00e3o.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Abra o <strong>Rastreador de Tempo<\/strong> ou a <strong>Planilha de horas<\/strong><\/li>\n\n\n\n<li>Navegue at\u00e9 a semana que deseja enviar<\/li>\n\n\n\n<li>Toque em Enviar<\/li>\n\n\n\n<li>Revise e confirme tocando em Enviar<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Todas as semanas enviadas ter\u00e3o Pendente ao lado delas. Para retirar um envio, toque na etiqueta pendente e clique em Retirar.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Todas as semanas aprovadas ter\u00e3o o r\u00f3tulo APROVADA pr\u00f3ximo a elas e as inscri\u00e7\u00f5es ter\u00e3o a marca de aprova\u00e7\u00e3o. Voc\u00ea n\u00e3o pode editar o tempo aprovado. Mas voc\u00ea pode adicionar novas entradas de tempo (se a semana n\u00e3o estiver\u00a0<a href=\"https:\/\/clockify.me\/help\/pt\/track-time-and-expenses\/lock-timesheets\">bloqueada<\/a>) e envi\u00e1-la para outra aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Caso haja <a href=\"https:\/\/clockify.me\/help\/track-time-and-expenses\/multiple-currencies\">m\u00faltiplas moedas<\/a> atribu\u00eddas a v\u00e1rios clientes, ao enviar despesas para aprova\u00e7\u00e3o, todas as moedas usadas ser\u00e3o listadas na tela <strong>Enviar para aprova\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"614\" height=\"442\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.54.08.png\" alt=\"\" class=\"wp-image-19864\" style=\"width:282px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.54.08.png 614w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.54.08-300x216.png 300w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.54.08-18x12.png 18w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Registro de despesas<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Abra Despesas na barra lateral (se voc\u00ea n\u00e3o v\u00ea-lo, certifique-se de ter <a href=\"https:\/\/clockify.me\/help\/pt\/track-time-and-expenses\/expenses\">Despesas<\/a> ativado nas configura\u00e7\u00f5es do espa\u00e7o de trabalho)<\/li>\n\n\n\n<li>Clique em + para adicionar uma nova despesa<\/li>\n\n\n\n<li>Selecione um projeto<\/li>\n\n\n\n<li>Selecione a categoria<\/li>\n\n\n\n<li>Insira o valor<\/li>\n\n\n\n<li>Escolha a data<\/li>\n\n\n\n<li>(Opcional) adicione uma observa\u00e7\u00e3o e\/ou recibo<\/li>\n<\/ol>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.56.55-472x1024.png\" alt=\"\" class=\"wp-image-19865\" style=\"width:253px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.56.55-472x1024.png 472w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.56.55-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.56.55-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.56.55.png 614w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.58.34-471x1024.png\" alt=\"\" class=\"wp-image-19866\" style=\"width:254px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.58.34-471x1024.png 471w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.58.34-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.58.34-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-13.58.34.png 614w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Anexar a fatura<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode anexar um recibo \u00e0s despesas de um projeto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao criar uma despesa:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Toque em <strong>Adicionar recibo<\/strong> no canto superior esquerdo<\/li>\n\n\n\n<li>Tire uma foto, escolha uma foto da biblioteca ou carregue o arquivo PDF<\/li>\n<\/ol>\n\n\n\n<p class=\"note wp-block-paragraph\">O tamanho m\u00e1ximo do arquivo carregado \u00e9 de 5 MB.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Adicionar projeto<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Toque em uma entrada<\/li>\n\n\n\n<li>Toque no campo Projeto<\/li>\n\n\n\n<li>Tap on the plus (+) at the top right corner<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.57.57-471x1024.png\" alt=\"\" class=\"wp-image-23680\" style=\"width:244px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.57.57-471x1024.png 471w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.57.57-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.57.57-707x1536.png 707w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.57.57-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-11.57.57.png 710w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.09.30-473x1024.png\" alt=\"\" class=\"wp-image-19868\" style=\"width:244px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.09.30-473x1024.png 473w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.09.30-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.09.30-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.09.30.png 614w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.10.48-470x1024.png\" alt=\"\" class=\"wp-image-19869\" style=\"width:242px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.10.48-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.10.48-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.10.48-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.10.48.png 612w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Adicionar cliente<\/h2>\n\n\n\n<p class=\"translation-block note wp-block-paragraph\">Os clientes podem ser criados somente na tela <strong>Projetos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para criar um novo cliente:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Toque no \u00edcone <strong>+<\/strong>\/<strong>reproduzir<\/strong> na tela do <strong>Rastreador de tempo<\/strong> para adicionar uma entrada de tempo <br>ou <br>Toque em uma entrada de tempo existente<\/li>\n\n\n\n<li>Escolha <strong>Projeto<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Toque no \u00edcone <strong>+<\/strong> no canto superior direito para criar um novo projeto<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Cliente<\/strong> para abrir a tela <strong>Clientes<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Toque no \u00edcone <strong>+<\/strong> no canto superior direito para criar um novo cliente<\/li>\n\n\n\n<li>Digite o nome do cliente<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Criar<\/strong> <strong>cliente<\/strong> para concluir a a\u00e7\u00e3o<\/li>\n<\/ol>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.02.27-470x1024.png\" alt=\"\" class=\"wp-image-23682\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.02.27-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.02.27-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.02.27-705x1536.png 705w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.02.27-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Screenshot-2025-06-26-at-12.02.27.png 708w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/adding_new_client-470x1024.png\" alt=\"\" class=\"wp-image-20024\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/adding_new_client-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/adding_new_client-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/adding_new_client-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/adding_new_client.png 610w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"470\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-11-at-09.12.38-470x1024.png\" alt=\"\" class=\"wp-image-20025\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-11-at-09.12.38-470x1024.png 470w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-11-at-09.12.38-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-11-at-09.12.38-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-11-at-09.12.38.png 610w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"translation-block tip wp-block-paragraph\">Por padr\u00e3o,\u00a0<strong>propriet\u00e1rios<\/strong>\u00a0e\u00a0<strong>administradores<\/strong>\u00a0podem criar clientes. No entanto, esse conjunto de permiss\u00f5es pode ser modificado. Confira o artigo de ajuda <a href=\"https:\/\/clockify.me\/help\/pt\/projects\/creating-projects#managing-clients\">Criar projetos e clientes no aplicativo da web<\/a> para obter mais informa\u00e7\u00f5es sobre quem pode criar clientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Relat\u00f3rios<\/h2>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">A tela de relat\u00f3rios mostra quanto tempo voc\u00ea acompanhou em cada dia e o detalhamento do projeto. \u00c9 equivalente ao <a href=\"https:\/\/clockify.me\/help\/pt\/reports\/dashboard\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre em uma nova aba)\">Painel<\/a> no aplicativo web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode escolher se deseja ver:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dados semanais, mensais, anuais ou de intervalo personalizado<\/li>\n\n\n\n<li>Seu tempo ou o tempo de toda a equipe<\/li>\n\n\n\n<li>Tempo gasto trabalhando em determinado projeto\/tarefa ou para determinado cliente <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.45.51-471x1024.png\" alt=\"\" class=\"wp-image-19872\" style=\"width:261px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.45.51-471x1024.png 471w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.45.51-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.45.51-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.45.51.png 612w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode arrastar para a esquerda no relat\u00f3rio para ver os dados da semana\/m\u00eas\/ano anterior ou para a direita para ver os dados da pr\u00f3xima semana\/m\u00eas\/ano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"903\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.18.21.png\" alt=\"\" class=\"wp-image-19870\" style=\"width:260px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.18.21.png 259w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.18.21-86x300.png 86w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><\/figure>\n\n\n\n<p class=\"note wp-block-paragraph\">Os membros regulares da equipe n\u00e3o poder\u00e3o ver os dados da equipe se voc\u00ea tiver desativado isso nas configura\u00e7\u00f5es do seu espa\u00e7o de trabalho.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Exportar relat\u00f3rio<\/h3>\n\n\n\n<div class=\"wp-block-custom-highlight-box custom-box color-green\"><div class=\"box-header\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask-green\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask-green)\"><path d=\"M5 21.0001C4.45 21.0001 3.97917 20.8043 3.5875 20.4126C3.19583 20.0209 3 19.5501 3 19.0001V5.0001C3 4.4501 3.19583 3.97926 3.5875 3.5876C3.97917 3.19593 4.45 3.0001 5 3.0001H13.925L11.925 5.0001H5V19.0001H19V12.0501L21 10.0501V19.0001C21 19.5501 20.8042 20.0209 20.4125 20.4126C20.0208 20.8043 19.55 21.0001 19 21.0001H5ZM9 15.0001V10.7501L18.175 1.5751C18.375 1.3751 18.6 1.2251 18.85 1.1251C19.1 1.0251 19.35 0.975098 19.6 0.975098C19.8667 0.975098 20.1208 1.0251 20.3625 1.1251C20.6042 1.2251 20.825 1.3751 21.025 1.5751L22.425 3.0001C22.6083 3.2001 22.75 3.42093 22.85 3.6626C22.95 3.90426 23 4.1501 23 4.4001C23 4.6501 22.9542 4.89593 22.8625 5.1376C22.7708 5.37926 22.625 5.6001 22.425 5.8001L13.25 15.0001H9ZM11 13.0001H12.4L18.2 7.2001L17.5 6.5001L16.775 5.8001L11 11.5751V13.0001Z\" fill=\"#4CAF50\"><\/path><\/g><\/svg><span class=\"box-label\">Nota<\/span><\/div><div class=\"box-content\">\n<p class=\"wp-block-paragraph\">Usu\u00e1rios do plano gratuito s\u00f3 podem exportar relat\u00f3rios referentes a um per\u00edodo de um m\u00eas e baix\u00e1-los em formato PDF.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Os relat\u00f3rios podem ser exportados e salvos nos formatos PDF, CSV ou Excel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para exportar um relat\u00f3rio:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Acesse a p\u00e1gina de <strong>Relat\u00f3rios<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Toque no bot\u00e3o <strong>exportar<\/strong> no canto superior direito.<\/li>\n\n\n\n<li>Selecione o formato que deseja baixar (PDF, CSV, Excel)<\/li>\n\n\n\n<li>Selecione o aplicativo que deseja usar para salvar o arquivo<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Export-report-iOS-576x1024.jpg\" alt=\"\" class=\"wp-image-29882\" style=\"aspect-ratio:0.5625026034073395;width:261px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Export-report-iOS-576x1024.jpg 576w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Export-report-iOS-169x300.jpg 169w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Export-report-iOS-7x12.jpg 7w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Export-report-iOS.jpg 750w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Compartilhar um relat\u00f3rio<\/h3>\n\n\n\n<div class=\"wp-block-custom-highlight-box custom-box color-green\"><div class=\"box-header\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask-green\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask-green)\"><path d=\"M5 21.0001C4.45 21.0001 3.97917 20.8043 3.5875 20.4126C3.19583 20.0209 3 19.5501 3 19.0001V5.0001C3 4.4501 3.19583 3.97926 3.5875 3.5876C3.97917 3.19593 4.45 3.0001 5 3.0001H13.925L11.925 5.0001H5V19.0001H19V12.0501L21 10.0501V19.0001C21 19.5501 20.8042 20.0209 20.4125 20.4126C20.0208 20.8043 19.55 21.0001 19 21.0001H5ZM9 15.0001V10.7501L18.175 1.5751C18.375 1.3751 18.6 1.2251 18.85 1.1251C19.1 1.0251 19.35 0.975098 19.6 0.975098C19.8667 0.975098 20.1208 1.0251 20.3625 1.1251C20.6042 1.2251 20.825 1.3751 21.025 1.5751L22.425 3.0001C22.6083 3.2001 22.75 3.42093 22.85 3.6626C22.95 3.90426 23 4.1501 23 4.4001C23 4.6501 22.9542 4.89593 22.8625 5.1376C22.7708 5.37926 22.625 5.6001 22.425 5.8001L13.25 15.0001H9ZM11 13.0001H12.4L18.2 7.2001L17.5 6.5001L16.775 5.8001L11 11.5751V13.0001Z\" fill=\"#4CAF50\"><\/path><\/g><\/svg><span class=\"box-label\">Nota<\/span><\/div><div class=\"box-content\">\n<p class=\"translation-block wp-block-paragraph\">Relat\u00f3rios compartilhados \u00e9 um recurso pago dispon\u00edvel em <a href=\"https:\/\/clockify.me\/pt\/pricing\">qualquer plano pago<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Gere um link para compartilhar relat\u00f3rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para compartilhar um relat\u00f3rio:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Acesse a p\u00e1gina de <strong>Relat\u00f3rios<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Toque no bot\u00e3o <strong>compartilhar<\/strong> no canto superior direito<\/li>\n\n\n\n<li>Insira um nome para o relat\u00f3rio<\/li>\n\n\n\n<li>Defina configura\u00e7\u00f5es opcionais, como visibilidade e datas de bloqueio<\/li>\n\n\n\n<li class=\"translation-block\">Toque em <strong>Compartilhar<\/strong><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Share-report-iOS-576x1024.jpg\" alt=\"\" class=\"wp-image-29883\" style=\"aspect-ratio:0.5625088805439967;width:251px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Share-report-iOS-576x1024.jpg 576w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Share-report-iOS-169x300.jpg 169w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Share-report-iOS-7x12.jpg 7w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/Share-report-iOS.jpg 750w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Op\u00e7\u00f5es de visibilidade<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode definir a seguinte visibilidade para seus relat\u00f3rios compartilhados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>P\u00fablico: Qualquer pessoa com o link pode visualizar (mesmo que n\u00e3o tenha uma conta Clockify).<\/li>\n\n\n\n<li>Privado: Vis\u00edvel apenas para membros do seu espa\u00e7o de trabalho que pertencem ao grupo atribu\u00eddo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Op\u00e7\u00f5es de intervalo de tempo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas op\u00e7\u00f5es permitem que voc\u00ea defina datas espec\u00edficas para os relat\u00f3rios que deseja compartilhar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\"><strong>Sempre aberto como na semana passada<\/strong>: O relat\u00f3rio ser\u00e1 exibido referente ao \u00faltimo dia, semana ou m\u00eas atual, dependendo do intervalo de datas definido para o relat\u00f3rio.<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Bloquear datas<\/strong>: Quando ativado, o usu\u00e1rio s\u00f3 poder\u00e1 visualizar o relat\u00f3rio para um intervalo de datas espec\u00edfico.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Relat\u00f3rios programado<\/strong><\/p>\n\n\n\n<p class=\"note translation-block wp-block-paragraph\">Os relat\u00f3rios agendados s\u00e3o um recurso pago dispon\u00edvel nos planos <a href=\"https:\/\/clockify.me\/pricing\">Pro e Enterprise<\/a>.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">O recurso <strong>Agendar envio por e-mail<\/strong> permite que administradores e propriet\u00e1rios de espa\u00e7os de trabalho agendem o envio de relat\u00f3rios para destinat\u00e1rios selecionados diariamente, semanalmente ou mensalmente.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Receber lembretes e notifica\u00e7\u00f5es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O aplicativo Clockify para iOS permite que voc\u00ea configure notifica\u00e7\u00f5es push para acompanhar seu controle de tempo sem precisar ficar monitorando o aplicativo constantemente. Voc\u00ea tamb\u00e9m pode tomar medidas diretamente a partir das notifica\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lembretes do cron\u00f4metro<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os lembretes do timer ajudam voc\u00ea a lembrar de iniciar ou parar o cron\u00f4metro novamente. Voc\u00ea pode personalizar os lembretes para adapt\u00e1-los \u00e0 sua agenda de trabalho.&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">V\u00e1 para o menu principal e abra <strong>Configura\u00e7\u00f5es<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Na se\u00e7\u00e3o <strong>Lembretes<\/strong>, ative a op\u00e7\u00e3o<\/li>\n\n\n\n<li>Escolha os dias e defina hor\u00e1rios espec\u00edficos em que deseja ser lembrado de iniciar\/parar o cron\u00f4metro<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"693\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-1.png\" alt=\"\" class=\"wp-image-26588\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-1.png 388w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-1-168x300.png 168w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-1-7x12.png 7w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado, voc\u00ea receber\u00e1 notifica\u00e7\u00f5es push nos hor\u00e1rios programados, mesmo que o aplicativo esteja fechado. As notifica\u00e7\u00f5es s\u00e3o acion\u00e1veis, ent\u00e3o voc\u00ea pode iniciar\/parar o cron\u00f4metro com um toque.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode desativar os lembretes a qualquer momento, desligando o interruptor.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Notifica\u00e7\u00f5es gerais<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode gerenciar todas as notifica\u00e7\u00f5es do seu aplicativo em um s\u00f3 lugar para evitar ser sobrecarregado por alertas desnecess\u00e1rios.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Abra o menu principal e toque em <strong>Configura\u00e7\u00f5es<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Selecione <strong>Notifica\u00e7\u00f5es<\/strong><\/li>\n\n\n\n<li>Aqui voc\u00ea pode ativar\/desativar tipos espec\u00edficos de alertas alternando o bot\u00e3o:\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\"><strong>Folga<\/strong>: Receba alertas sobre solicita\u00e7\u00f5es de folga e atualiza\u00e7\u00f5es<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Planejador<\/strong>: Mantenha-se informado sobre altera\u00e7\u00f5es na sua agenda&nbsp;&nbsp;<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"389\" height=\"292\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-3.png\" alt=\"\" class=\"wp-image-26590\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-3.png 389w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-3-300x225.png 300w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-3-16x12.png 16w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Emblemas no aplicativo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os emblemas no aplicativo ajudam voc\u00ea a se manter informado sobre atualiza\u00e7\u00f5es importantes rapidamente.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\"><strong>Emblemas de \u00edcones de aplicativos<\/strong>: Um emblema indicar\u00e1 se h\u00e1 notifica\u00e7\u00f5es n\u00e3o lidas de itens que exigem sua aten\u00e7\u00e3o. Assim que os itens forem revisados \u200b\u200bou acionados, o emblema desaparecer\u00e1.&nbsp;<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Alertas de folga<\/strong>: Um indicador aparece no canto superior esquerdo da tela quando h\u00e1 uma solicita\u00e7\u00e3o de folga pendente que requer a aten\u00e7\u00e3o do usu\u00e1rio. Dessa forma, gerentes e administradores podem acompanhar as aprova\u00e7\u00f5es.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"317\" height=\"648\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-2.png\" alt=\"\" class=\"wp-image-26589\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-2.png 317w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-2-147x300.png 147w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-2-6x12.png 6w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Importante observar<\/strong>:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lembretes e notifica\u00e7\u00f5es s\u00e3o desativados no modo offline<\/li>\n\n\n\n<li>Se voc\u00ea for membro de v\u00e1rios espa\u00e7os de trabalho, poder\u00e1 definir lembretes para cada um e receb\u00ea-los para todos os seus espa\u00e7os de trabalho selecionados.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Configura\u00e7\u00f5es do perfil<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao tocar no nome da sua conta no menu lateral, voc\u00ea ver\u00e1 sua p\u00e1gina de perfil, onde poder\u00e1 gerenciar sua conta e configura\u00e7\u00f5es pessoais.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"910\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-4.png\" alt=\"\" class=\"wp-image-26591\" style=\"width:250px\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-4.png 390w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-4-129x300.png 129w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2018\/02\/image-4-5x12.png 5w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Perfil e conta<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alternar sua foto de perfil<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Gerenciar conta da CAKE.com<\/strong> redireciona o usu\u00e1rio para configura\u00e7\u00f5es mais amplas da conta CAKE.com<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Sair<\/strong> da sua conta<\/li>\n\n\n\n<li><strong>Deletar uma conta<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">A op\u00e7\u00e3o <strong>Excluir conta<\/strong> redireciona voc\u00ea para a p\u00e1gina de <strong>gerenciamento de conta da CAKE.com<\/strong>, onde voc\u00ea pode concluir esta a\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Para mais informa\u00e7\u00f5es sobre como excluir sua conta, confira <a href=\"https:\/\/cake.com\/help\/administration\/deactivate-and-delete-user-account\/\">este <\/a>artigo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Configura\u00e7\u00f5es de data e hora<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Na se\u00e7\u00e3o <strong>Data e hora<\/strong> da p\u00e1gina, voc\u00ea pode personalizar suas prefer\u00eancias:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rel\u00f3gio de 24 horas (ativar\/desativar)<\/li>\n\n\n\n<li class=\"translation-block\">Defina o seu <strong>In\u00edcio da Semana<\/strong> (por exemplo, segunda ou ter\u00e7a-feira)<\/li>\n\n\n\n<li class=\"translation-block\">Definir o seu <strong>in\u00edcio do dia<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Definir seu <strong>fuso hor\u00e1rio<\/strong> automaticamente ou escolha defini-lo manualmente<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Configura\u00e7\u00f5es (Geral)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao clicar no menu Configura\u00e7\u00f5es na barra lateral, voc\u00ea ver\u00e1 uma tela de configura\u00e7\u00f5es gerais, onde poder\u00e1:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"translation-block\">Habilite a op\u00e7\u00e3o de adicionar a etiqueta <strong>m\u00f3vel<\/strong> a cada entrada de tempo criada no seu telefone<\/li>\n\n\n\n<li class=\"translation-block\">Autentica\u00e7\u00e3o de dois fatores (2FA)<\/li>\n\n\n\n<li class=\"translation-block\"><a href=\"https:\/\/clockify.me\/help\/pt\/apps\/iphone-app#app-theme\">Tema do aplicativo<\/a><\/li>\n\n\n\n<li class=\"translation-block\"><a href=\"https:\/\/clockify.me\/help\/pt\/apps\/iphone-app#default-project\">Projeto padr\u00e3o<\/a><\/li>\n\n\n\n<li class=\"translation-block\"><a href=\"https:\/\/clockify.me\/help\/pt\/apps\/android-app#offline-mode\">For\u00e7ar modo offline<\/a><\/li>\n\n\n\n<li class=\"translation-block\"><a href=\"https:\/\/clockify.me\/help\/pt\/apps\/iphone-app#calendar\">Integra\u00e7\u00e3o de calend\u00e1rio<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"1024\" src=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.54.10-472x1024.png\" alt=\"\" class=\"wp-image-19874\" style=\"width:250px;height:auto\" srcset=\"https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.54.10-472x1024.png 472w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.54.10-138x300.png 138w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.54.10-6x12.png 6w, https:\/\/clockify.me\/help\/wp-content\/uploads\/2024\/08\/Screenshot-2024-08-27-at-14.54.10.png 614w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Tema do aplicativo<\/h3>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Voc\u00ea pode definir um tema que corresponda ao sistema. Por padr\u00e3o, quando voc\u00ea instala o aplicativo, o tema do aplicativo \u00e9 definido como <strong>Padr\u00e3o do sistema<\/strong>. Caso queira alterar o tema padr\u00e3o, voc\u00ea pode fazer isso na tela de <strong> Configura\u00e7\u00f5es<\/strong>  e escolher uma das seguintes op\u00e7\u00f5es:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Sistema padr\u00e3o<\/li>\n\n\n\n<li>Claro <\/li>\n\n\n\n<li>Escuro<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">O tema ser\u00e1 aplicado imediatamente<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Projeto padr\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea costuma trabalhar no mesmo projeto, pode defin\u00ed-lo como padr\u00e3o. Ent\u00e3o, tudo o que voc\u00ea precisa fazer \u00e9 digitar no que est\u00e1 trabalhando e iniciar o cron\u00f4metro, e o projeto ser\u00e1 selecionado automaticamente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode definir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Um projeto fixo, que sempre ser\u00e1 usado quando voc\u00ea iniciar um cron\u00f4metro para uma entrada n\u00e3o relacionada ao projeto (at\u00e9 que voc\u00ea altere o projeto padr\u00e3o)<\/li>\n\n\n\n<li class=\"translation-block\">Ou selecione <strong>\u00daltimo projeto usado<\/strong>, e o cron\u00f4metro usar\u00e1 o \u00faltimo projeto dispon\u00edvel da sua lista de entradas de tempo<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Modo offline<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode rastrear o tempo no Clockify no seu iPhone, mesmo se estiver desconectado. Voc\u00ea pode criar as entradas de tempo manualmente ou iniciar\/parar o cron\u00f4metro, e as novas entradas criadas desta forma ser\u00e3o salvas localmente em seu telefone. Quando voc\u00ea se reconectar, o aplicativo vai sincronizar automaticamente todas as entradas de tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando estiver desconectado, voc\u00ea s\u00f3 poder\u00e1 ver as informa\u00e7\u00f5es que foram carregadas quando voc\u00ea estava online (registros de tempo, projetos, tarefas, etiquetas etc.). Portanto, projetos, tarefas e etiquetas estar\u00e3o dispon\u00edveis apenas se tiverem sido carregados antes de voc\u00ea ficar desconectado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Novos projetos, tarefas, etiquetas e clientes n\u00e3o podem ser criados offline.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Se voc\u00ea notar que o aplicativo est\u00e1 muito lento, provavelmente significa que sua conex\u00e3o de internet est\u00e1 inst\u00e1vel. Nesse caso, ative <strong>For\u00e7ar modo offline<\/strong> nas Configura\u00e7\u00f5es para melhorar o desempenho. Isso far\u00e1 com que o aplicativo se comporte como se estivesse offline sem que voc\u00ea precise desligar a conex\u00e3o de internet. Ap\u00f3s desativar <strong>For\u00e7ar modo offline<\/strong>, o aplicativo sincronizar\u00e1 automaticamente todas as entradas de tempo.<\/p>\n\n\n\n<p class=\"note translation-block wp-block-paragraph\">Se voc\u00ea estiver usando o aplicativo no <strong>modo offline<\/strong>, certifique-se de sincronizar suas entradas de tempo com a nuvem antes de sair. Caso contr\u00e1rio, todos os dados que n\u00e3o estiverem sincronizados no momento do logout ser\u00e3o perdidos.<\/p>\n\n\n\n<div class=\"wp-block-group related-articles\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Artigos relacionados<\/h3>\n\n\n\n<ul class=\"wp-block-list related-articles-list\">\n<li class=\"translation-block\"><a href=\"https:\/\/clockify.me\/help\/pt\/apps\/android-app\">Aplicativo para Android<\/a><\/li>\n\n\n\n<li class=\"translation-block\"><a href=\"https:\/\/clockify.me\/help\/pt\/getting-started\/system-requirements-for-using-clockify\">Requisitos do sistema para usar o Clockify\n<\/a><\/li>\n<\/ul>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Install Clockify on your iPhone or iPad and track time while on the go. Download&#8230;","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_helpful_status":1,"_searchwp_excluded":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-380","post","type-post","status-publish","format-standard","hentry","category-mobile"],"acf":[],"featured_image_src":null,"author_info":{"display_name":"helpadmin","author_link":"https:\/\/clockify.me\/help\/pt\/author\/helpadmin"},"_links":{"self":[{"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/posts\/380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/comments?post=380"}],"version-history":[{"count":432,"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/posts\/380\/revisions"}],"predecessor-version":[{"id":33127,"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/posts\/380\/revisions\/33127"}],"wp:attachment":[{"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/media?parent=380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/categories?post=380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clockify.me\/help\/pt\/wp-json\/wp\/v2\/tags?post=380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}